{"id":11654,"date":"2022-11-09T09:00:00","date_gmt":"2022-11-09T12:00:00","guid":{"rendered":"https:\/\/www.agenciainfra.com\/blog\/?p=11654"},"modified":"2022-11-09T15:26:05","modified_gmt":"2022-11-09T18:26:05","slug":"inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos","status":"publish","type":"post","link":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/","title":{"rendered":"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>Dimmi Amora, da Ag\u00eancia iNFRA<\/strong><\/p>\n\n\n\n<p>A concess\u00e3o do Porto de Santos (SP) com a previs\u00e3o de que seja constru\u00eddo um t\u00fanel entre Santos e Guaruj\u00e1, com futura cobran\u00e7a de ped\u00e1gio, amplia significativamente o risco do projeto e faz com que o valor estimativo dessa concess\u00e3o se reduza em R$ 0,5 bilh\u00e3o.<br><br>A constata\u00e7\u00e3o est\u00e1 no relat\u00f3rio da SeinfraPortoFerrovia do TCU (Tribunal de Contas da Uni\u00e3o) que avaliou os estudos de viabilidade para a concess\u00e3o do maior porto do pa\u00eds. O relat\u00f3rio foi conclu\u00eddo no \u00faltimo domingo (6) e entregue ao relator do processo, ministro Bruno Dantas. Cabe a ele agora pautar ou n\u00e3o o processo em plen\u00e1rio.<br><br>&#8220;Sob\u00a0o prisma puramente financeiro, a mera inclus\u00e3o do t\u00fanel na concess\u00e3o resultou em um aumento do risco sist\u00eamico do projeto, medido pelo beta (desalavancado), da ordem de 27,7%. Esse valor representa um pr\u00eamio de risco maior, a ser custeado pelo poder p\u00fablico, para compensar o privado pelos maiores riscos tomados&#8221;, informa o relat\u00f3rio.<br><br>O pr\u00f3prio governo j\u00e1 calculou esse pr\u00eamio de risco maior e reduziu o valor m\u00ednimo de outorga da concess\u00e3o de R$ 3,015 bilh\u00f5es para R$ 2,557 bilh\u00f5es, quase R$ 500 milh\u00f5es a menos.\u00a0<br><br>&#8220;O principal fator que levou a esta redu\u00e7\u00e3o relaciona-se ao incremento do pr\u00eamio de risco inclu\u00eddo na composi\u00e7\u00e3o da taxa de desconto, por meio do beta, em virtude da percep\u00e7\u00e3o de que o risco do projeto\u00a0como um todo aumentou consideravelmente pela inclus\u00e3o da obriga\u00e7\u00e3o de execu\u00e7\u00e3o e opera\u00e7\u00e3o da liga\u00e7\u00e3o seca Santos-Guaruj\u00e1, especialmente devido \u00e0s fragilidades de seu projeto e modelagem mencionadas ao longo deste relat\u00f3rio&#8221;, informa um trecho do documento.<br><br>O projeto que baseou o custo da obra, de R$ 4,2 bi, o que corresponde a cerca de 2\/3 de todos os investimentos previstos nessa concess\u00e3o, s\u00e3o de baixa maturidade, segundo o relat\u00f3rio, o que \u00e9 apontado pelo pr\u00f3prio BNDES, respons\u00e1vel pelos estudos. A alternativa escolhida de incluir o t\u00fanel na concess\u00e3o, segundo o relat\u00f3rio, &#8220;n\u00e3o foi escolhida por basear-se em motivos t\u00e9cnicos que indiquem que seja a melhor op\u00e7\u00e3o para o projeto, mas sim por se tratar da alternativa que representava menores riscos para a conclus\u00e3o do processo de desestatiza\u00e7\u00e3o no cronograma planejado pelo Governo, ainda em 2022&#8221;.<br><br><strong>Atualiza\u00e7\u00e3o da planilha<\/strong><br>Para tentar reduzir ainda mais esse risco, os t\u00e9cnicos sugeriram ao relator uma determina\u00e7\u00e3o espec\u00edfica a ser encaminhada ao Minist\u00e9rio da Infraestrutura, o que significa algo que, se referendado pelo plen\u00e1rio do \u00f3rg\u00e3o, ter\u00e1 que ser implementado antes de levar o edital ao p\u00fablico:\u00a0uma atualiza\u00e7\u00e3o da planilha or\u00e7ament\u00e1ria do projeto do t\u00fanel, que deve estar publicada juntamente com o edital.<br><br>Um engenheiro com conhecimento do projeto disse que \u00e9 uma tarefa complexa para ser feita em prazo curto. Mas alerta que o governo j\u00e1 vinha recebendo indicativos de que isso teria que ser feito e, por isso, acha poss\u00edvel que a atualiza\u00e7\u00e3o seja feita dentro do prazo que o governo diz que precisa para colocar o leil\u00e3o na rua neste ano, que seria publicar o edital at\u00e9 o fim deste m\u00eas. Essa avalia\u00e7\u00e3o \u00e9 corroborada tamb\u00e9m entre integrantes do TCU.\u00a0<br><br>Mas a avalia\u00e7\u00e3o \u00e9 que, mesmo que essa atualiza\u00e7\u00e3o seja conclu\u00edda, isso n\u00e3o vai tirar totalmente os riscos do projeto, que s\u00e3o avaliados como muito elevados em praticamente todo o documento de mais de 120 p\u00e1ginas elaborado pelos auditores do tribunal. Para aumentar ainda mais esse risco, os auditores relatam em v\u00e1rios momentos que, por causa da &#8220;celeridade requerida pelo relator&#8221;, n\u00e3o conseguiram aprofundar as an\u00e1lises de alguns pontos.<br><br>Al\u00e9m da determina\u00e7\u00e3o sobre o t\u00fanel (e uma outra sobre regras de contrata\u00e7\u00e3o de verificador independente), os auditores sugeriram tamb\u00e9m outras recomenda\u00e7\u00f5es para adaptar o projeto. Essas recomenda\u00e7\u00f5es podem ou n\u00e3o ser acatadas pelo relator ou at\u00e9 serem transformadas em determina\u00e7\u00f5es na an\u00e1lise do plen\u00e1rio.<br><br>Uma delas trata da pol\u00edtica tarif\u00e1ria para o t\u00fanel Santos-Guaruj\u00e1. Isso porque, de acordo com a avalia\u00e7\u00e3o, os estudos de demanda da concess\u00e3o do t\u00fanel foram considerados incipientes e podem estar com uma tarifa prevista pelo menos 18% defasada, de acordo com o relat\u00f3rio.<br><br><strong>STS10<\/strong><br>Os problemas com o t\u00fanel, contudo, n\u00e3o s\u00e3o os \u00fanicos apontados pelos auditores do tribunal. Eles tamb\u00e9m fizeram recomenda\u00e7\u00f5es sobre os problemas competitivos em rela\u00e7\u00e3o ao futuro concession\u00e1rio do porto, especialmente em rela\u00e7\u00e3o ao novo terminal de cont\u00eaineres (STS10), previsto para ser arrendado pelo futuro concession\u00e1rio.<br><br>A recomenda\u00e7\u00e3o prev\u00ea que a ANTAQ (Ag\u00eancia Nacional de Transportes Aquavi\u00e1rios)\u00a0e o Cade (Conselho Administrativo de Defesa Econ\u00f4mica)\u00a0atuem de forma conjunta em v\u00e1rios itens, como na &#8220;aprova\u00e7\u00e3o do c\u00f3digo de conduta da concession\u00e1ria, nos termos do Anexo 11 do contrato de concess\u00e3o&#8221; e no &#8220;estudo que caracterize objetivamente as condutas abusivas da concession\u00e1ria quando da utiliza\u00e7\u00e3o de seu poder de mercado na negocia\u00e7\u00e3o de renova\u00e7\u00f5es e novos contratos com exploradores de instala\u00e7\u00f5es portu\u00e1rias, bem como para evitar que tais negocia\u00e7\u00f5es falseiem ou limitem o grau de contestabilidade dos mercados&#8221;.<br><br><strong>Caso de Itaja\u00ed<\/strong><br>No caso da competi\u00e7\u00e3o do mercado de cont\u00eaineres, o indicativo de que o TCU ter\u00e1 uma postura menos favor\u00e1vel \u00e0 verticaliza\u00e7\u00e3o das cadeias veio na an\u00e1lise t\u00e9cnica de outro processo de concess\u00e3o, o do porto de Itaja\u00ed (SC), finalizado no fim do m\u00eas passado. O processo agora est\u00e1 nas m\u00e3os do relator, ministro Walton Alencar, para ser pautado em plen\u00e1rio.<br><br>No documento, os auditores indicam que n\u00e3o concordam com os estudos que est\u00e3o baseando o governo a realizar licita\u00e7\u00f5es de terminais portu\u00e1rios de cont\u00eaineres sem maiores restri\u00e7\u00f5es \u00e0 participa\u00e7\u00e3o de empresas pertencentes a grandes armadores internacionais, feitos pela antiga EPL (Empresa de Planejamento e Log\u00edstica), hoje Infra S.A.<br><br>O parecer se alinha aos estudos feitos pela Seae (Secretaria de Acompanhamento Econ\u00f4mico) do Minist\u00e9rio da Economia, que indica ser preferencial, no momento, a imposi\u00e7\u00e3o de restri\u00e7\u00f5es maiores \u00e0 participa\u00e7\u00e3o de armadores nos terminais de cont\u00eaineres, como forma de melhorar o ambiente concorrencial do setor.<br><br>&#8220;Contudo, dada a m\u00e1xima v\u00eania, a equipe t\u00e9cnica deve discordar de tal decis\u00e3o [da EPL], pois entende que a recomenda\u00e7\u00e3o da Seae traduz o desenho licitat\u00f3rio mais adequado para o caso em tela, tendo em vista a assun\u00e7\u00e3o pelo poder p\u00fablico de potenciais riscos para o ambiente concorrencial em eventual outorga do objeto licitat\u00f3rio para os Grupos Maersk ou MSC&#8221;,\u00a0diz o texto.<br><br><strong>Restri\u00e7\u00e3o na concorr\u00eancia<\/strong><br>A sugest\u00e3o apresentada ao relator \u00e9 que a licita\u00e7\u00e3o do porto de Itaja\u00ed seja feita\u00a0na primeira fase sem possibilidade de participa\u00e7\u00e3o de grupos econ\u00f4micos pertencentes \u00e0 Alian\u00e7a 2M + H, formada pela Maersk, MSC e Hyundai. Empresas que pertencem a esses grupos j\u00e1 controlam alguns terminais portu\u00e1rios no pa\u00eds, entre eles o de Navegantes, que fica em frente ao de Itaja\u00ed.<br><br>A proposta \u00e9 que, somente em caso de n\u00e3o haver interessados na primeira rodada, a licita\u00e7\u00e3o passe a contar com uma segunda rodada em que qualquer grupo econ\u00f4mico poder\u00e1 participar. A proposta indica que, em caso de n\u00e3o ado\u00e7\u00e3o do modelo proposto, &#8220;o Minfra deve motivar sua op\u00e7\u00e3o, por meio da reavalia\u00e7\u00e3o do estudo concorrencial, enfrentando as fragilidades e riscos apontados&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dimmi Amora, da Ag\u00eancia iNFRA A concess\u00e3o do Porto de Santos (SP) com a previs\u00e3o de que seja constru\u00eddo um t\u00fanel entre Santos e Guaruj\u00e1, com futura cobran\u00e7a de ped\u00e1gio, amplia significativamente o risco do projeto e faz com que o valor estimativo dessa concess\u00e3o se reduza em R$ 0,5 bilh\u00e3o. A constata\u00e7\u00e3o est\u00e1 no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1,7],"tags":[86,103,396,371,22,192,252,6026,1057,775,5457,2056,260,3827,4101,18,1634,5535,1204],"class_list":["post-11654","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-infratransporte","tag-antaq","tag-bndes","tag-bruno-dantas","tag-cade","tag-concessao","tag-desestatizacao","tag-epl","tag-hyundai","tag-maersk","tag-ministerio-da-infraestrutura","tag-msc","tag-porto-de-itajai","tag-porto-de-santos","tag-seae","tag-sts10","tag-tcu","tag-terminal-de-conteineres","tag-tunel-santos-guaruja","tag-walton-alencar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v26.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos - Ag\u00eancia iNFRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos\" \/>\n<meta property=\"og:description\" content=\"Dimmi Amora, da Ag\u00eancia iNFRA A concess\u00e3o do Porto de Santos (SP) com a previs\u00e3o de que seja constru\u00eddo um t\u00fanel entre Santos e Guaruj\u00e1, com futura cobran\u00e7a de ped\u00e1gio, amplia significativamente o risco do projeto e faz com que o valor estimativo dessa concess\u00e3o se reduza em R$ 0,5 bilh\u00e3o. A constata\u00e7\u00e3o est\u00e1 no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/\" \/>\n<meta property=\"og:site_name\" content=\"Ag\u00eancia iNFRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ageninfra\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-09T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-09T18:26:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"749\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Ag\u00eancia iNFRA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@agencia_infra\" \/>\n<meta name=\"twitter:site\" content=\"@agencia_infra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ag\u00eancia iNFRA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/\"},\"author\":{\"name\":\"Ag\u00eancia iNFRA\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/34af08dff6adea4cb22b06612ba7acfa\"},\"headline\":\"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos\",\"datePublished\":\"2022-11-09T12:00:00+00:00\",\"dateModified\":\"2022-11-09T18:26:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/\"},\"wordCount\":1324,\"publisher\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png\",\"keywords\":[\"ANTAQ\",\"BNDES\",\"Bruno Dantas\",\"Cade\",\"Concess\u00e3o\",\"desestatiza\u00e7\u00e3o\",\"EPL\",\"Hyundai\",\"Maersk\",\"Minist\u00e9rio da Infraestrutura\",\"MSC\",\"Porto de Itaja\u00ed\",\"Porto de Santos\",\"Seae\",\"STS10\",\"TCU\",\"terminal de cont\u00eaineres\",\"t\u00fanel Santos-Guaruj\u00e1\",\"Walton Alencar\"],\"articleSection\":[\"Geral\",\"iNFRATransporte\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/\",\"url\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/\",\"name\":\"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos - Ag\u00eancia iNFRA\",\"isPartOf\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png\",\"datePublished\":\"2022-11-09T12:00:00+00:00\",\"dateModified\":\"2022-11-09T18:26:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#primaryimage\",\"url\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png\",\"contentUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png\",\"width\":1280,\"height\":749,\"caption\":\"Foto: Reprodu\u00e7\u00e3o\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/agenciainfra.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#website\",\"url\":\"https:\/\/agenciainfra.com\/blog\/\",\"name\":\"Ag\u00eancia iNFRA\",\"description\":\"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!\",\"publisher\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agenciainfra.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\",\"name\":\"Ag\u00eancia iNFRA\",\"url\":\"https:\/\/agenciainfra.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png\",\"contentUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png\",\"width\":1672,\"height\":454,\"caption\":\"Ag\u00eancia iNFRA\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ageninfra\",\"https:\/\/x.com\/agencia_infra\",\"https:\/\/www.linkedin.com\/company\/ag\u00eanciainfra\/\",\"https:\/\/www.instagram.com\/agenciainfra\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/34af08dff6adea4cb22b06612ba7acfa\",\"name\":\"Ag\u00eancia iNFRA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d189e01678f06d8eb84d4e01f08eb848b3fffe3f8443818d3c356c66892f5be8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d189e01678f06d8eb84d4e01f08eb848b3fffe3f8443818d3c356c66892f5be8?s=96&d=mm&r=g\",\"caption\":\"Ag\u00eancia iNFRA\"},\"url\":\"https:\/\/agenciainfra.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos - Ag\u00eancia iNFRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/","og_locale":"pt_BR","og_type":"article","og_title":"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos","og_description":"Dimmi Amora, da Ag\u00eancia iNFRA A concess\u00e3o do Porto de Santos (SP) com a previs\u00e3o de que seja constru\u00eddo um t\u00fanel entre Santos e Guaruj\u00e1, com futura cobran\u00e7a de ped\u00e1gio, amplia significativamente o risco do projeto e faz com que o valor estimativo dessa concess\u00e3o se reduza em R$ 0,5 bilh\u00e3o. A constata\u00e7\u00e3o est\u00e1 no [&hellip;]","og_url":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/","og_site_name":"Ag\u00eancia iNFRA","article_publisher":"https:\/\/www.facebook.com\/ageninfra","article_published_time":"2022-11-09T12:00:00+00:00","article_modified_time":"2022-11-09T18:26:05+00:00","og_image":[{"width":1280,"height":749,"url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png","type":"image\/png"}],"author":"Ag\u00eancia iNFRA","twitter_card":"summary_large_image","twitter_creator":"@agencia_infra","twitter_site":"@agencia_infra","twitter_misc":{"Escrito por":"Ag\u00eancia iNFRA","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#article","isPartOf":{"@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/"},"author":{"name":"Ag\u00eancia iNFRA","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/34af08dff6adea4cb22b06612ba7acfa"},"headline":"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos","datePublished":"2022-11-09T12:00:00+00:00","dateModified":"2022-11-09T18:26:05+00:00","mainEntityOfPage":{"@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/"},"wordCount":1324,"publisher":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png","keywords":["ANTAQ","BNDES","Bruno Dantas","Cade","Concess\u00e3o","desestatiza\u00e7\u00e3o","EPL","Hyundai","Maersk","Minist\u00e9rio da Infraestrutura","MSC","Porto de Itaja\u00ed","Porto de Santos","Seae","STS10","TCU","terminal de cont\u00eaineres","t\u00fanel Santos-Guaruj\u00e1","Walton Alencar"],"articleSection":["Geral","iNFRATransporte"],"inLanguage":"pt-BR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/","url":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/","name":"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos - Ag\u00eancia iNFRA","isPartOf":{"@id":"https:\/\/agenciainfra.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#primaryimage"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#primaryimage"},"thumbnailUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png","datePublished":"2022-11-09T12:00:00+00:00","dateModified":"2022-11-09T18:26:05+00:00","breadcrumb":{"@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#primaryimage","url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png","contentUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2022\/09\/tunel-santos-guaruja-foto-vou-de-tunel-reproducao.png","width":1280,"height":749,"caption":"Foto: Reprodu\u00e7\u00e3o"},{"@type":"BreadcrumbList","@id":"https:\/\/agenciainfra.com\/blog\/inclusao-de-tunel-aumenta-risco-e-reduz-em-r-05-bi-outorga-da-concessao-do-porto-de-santos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/agenciainfra.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Inclus\u00e3o de t\u00fanel aumenta risco e reduz em R$ 0,5 bi outorga da concess\u00e3o do Porto de Santos"}]},{"@type":"WebSite","@id":"https:\/\/agenciainfra.com\/blog\/#website","url":"https:\/\/agenciainfra.com\/blog\/","name":"Ag\u00eancia iNFRA","description":"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!","publisher":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agenciainfra.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/agenciainfra.com\/blog\/#organization","name":"Ag\u00eancia iNFRA","url":"https:\/\/agenciainfra.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","contentUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","width":1672,"height":454,"caption":"Ag\u00eancia iNFRA"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ageninfra","https:\/\/x.com\/agencia_infra","https:\/\/www.linkedin.com\/company\/ag\u00eanciainfra\/","https:\/\/www.instagram.com\/agenciainfra\/"]},{"@type":"Person","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/34af08dff6adea4cb22b06612ba7acfa","name":"Ag\u00eancia iNFRA","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d189e01678f06d8eb84d4e01f08eb848b3fffe3f8443818d3c356c66892f5be8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d189e01678f06d8eb84d4e01f08eb848b3fffe3f8443818d3c356c66892f5be8?s=96&d=mm&r=g","caption":"Ag\u00eancia iNFRA"},"url":"https:\/\/agenciainfra.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts\/11654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/comments?post=11654"}],"version-history":[{"count":0,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts\/11654\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/media\/11324"}],"wp:attachment":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/media?parent=11654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/categories?post=11654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/tags?post=11654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}