{"id":3641,"date":"2019-08-28T08:00:58","date_gmt":"2019-08-28T11:00:58","guid":{"rendered":"http:\/\/www.agenciainfra.com\/blog\/?p=3641"},"modified":"2019-08-27T10:40:44","modified_gmt":"2019-08-27T13:40:44","slug":"governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro","status":"publish","type":"post","link":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/","title":{"rendered":"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro"},"content":{"rendered":"<h5 style=\"text-align: right;\"><strong>Leila Coimbra,\u00a0da Ag\u00eancia iNFRA<\/strong><\/h5>\n<p>O MME (Minist\u00e9rio de Minas e Energia) vai propor\u00a0uma mudan\u00e7a radical nos formatos dos pr\u00f3ximos leil\u00f5es de gera\u00e7\u00e3o de energia, dividindo em at\u00e9 tr\u00eas produtos diferentes o que hoje \u00e9 feito em uma \u00fanica contrata\u00e7\u00e3o.<\/p>\n<p>Primeiro, a ideia \u00e9 separar o lastro \u2013 capacidade total de produzir eletricidade, em MW\u00a0\u2013 do produto energia \u2013 quantidade f\u00edsica que os equipamentos produzem. Por sua vez, o lastro seria dividido em outros dois subprodutos: lastro de capacidade e lastro de produ\u00e7\u00e3o.<\/p>\n<p>O objetivo \u00e9 realizar leil\u00f5es separados para cada produto com a sua precifica\u00e7\u00e3o. Mas todos seriam contratados ao mesmo tempo. A CP (Consulta P\u00fablica) com as novas regras ser\u00e1 aberta pelo MME nos pr\u00f3ximos dias para acatar as sugest\u00f5es do mercado.<\/p>\n<p><strong>Diferen\u00e7a entre produ\u00e7\u00e3o e capacidade<\/strong><br \/>\nA diferen\u00e7a entre os dois subprodutos do lastro\u00a0(produ\u00e7\u00e3o e capacidade ) \u00e9 a seguinte: enquanto o lastro de produ\u00e7\u00e3o \u00e9 para o atendimento da demanda de eletricidade de forma acumulada ao longo de um determinado intervalo de tempo, o lastro de capacidade visa o atendimento da demanda de eletricidade em instantes.<\/p>\n<p><strong>Garantia f\u00edsica:<\/strong><br \/>\nAtualmente, os geradores vendem sua garantia f\u00edsica de energia nos leil\u00f5es (GF) em um contrato \u00fanico, e a receita dos agentes est\u00e1 atrelada \u00e0 GF dos empreendimentos. Na an\u00e1lise do governo, feita pela EPE (Empresa de Pesquisa Energ\u00e9tica), os c\u00e1lculos atuais da GF s\u00e3o incompat\u00edveis com os v\u00e1rios perfis de risco do segmento de gera\u00e7\u00e3o.<\/p>\n<p>Isso prejudica a forma\u00e7\u00e3o de pre\u00e7o de novos produtos necess\u00e1rios para o abastecimento do sistema, segundo a empresa de pesquisa.<\/p>\n<p><strong>Projeto de Lei<\/strong><br \/>\nA implementa\u00e7\u00e3o dessa mudan\u00e7a nos leil\u00f5es seria feita por meio de lei. Existe a possibilidade de inclus\u00e3o da medida em algum dos projetos de lei que tramitam no Congresso \u2013 e tratam da moderniza\u00e7\u00e3o do setor. A\u00a0 separa\u00e7\u00e3o entre lastro e energia est\u00e1 em linha com o que prop\u00f5e a CP 33, na avalia\u00e7\u00e3o da EPE.<\/p>\n<p><strong>Tempo de transi\u00e7\u00e3o<\/strong><br \/>\nCaso a separa\u00e7\u00e3o dos produtos no leil\u00e3o seja efetivamente proposta pelo Executivo e aprovada pelo Legislativo, haver\u00e1, depois disso, um longo per\u00edodo de transi\u00e7\u00e3o, respeitando os contratos legados.<\/p>\n<p>Ap\u00f3s a san\u00e7\u00e3o da lei, \u00e9 preciso ainda a regulamenta\u00e7\u00e3o, organiza\u00e7\u00e3o de regras e de procedimentos. A entrada em vigor ser\u00e1 bastante gradual.<\/p>\n<p><strong>Mudan\u00e7a na matriz<\/strong><br \/>\nNo passado, com uma matriz baseada em hidrel\u00e9tricas com grandes reservat\u00f3rios, bastava garantir a expans\u00e3o por meio de leil\u00f5es de energia, sem o lastro. Atualmente, por\u00e9m, sem \u00e1gua suficiente, essas hidrel\u00e9tricas j\u00e1 n\u00e3o t\u00eam capacidade de gerar como antigamente, expondo a diferen\u00e7a entre o lastro e a energia.<\/p>\n<p>Al\u00e9m disso, a nova matriz tem agora gera\u00e7\u00e3o e\u00f3lica, fotovoltaica e hidrel\u00e9tricas a fio d\u2019\u00e1gua \u2013 fontes com grande diferen\u00e7a entre capacidade total de gera\u00e7\u00e3o e a garantia f\u00edsica. Esse cen\u00e1rio leva \u00e0 necessidade de mudan\u00e7as no c\u00e1lculo de suprimento e de forma\u00e7\u00e3o de pre\u00e7os, diz o relat\u00f3rio da empresa de pesquisa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leila Coimbra,\u00a0da Ag\u00eancia iNFRA O MME (Minist\u00e9rio de Minas e Energia) vai propor\u00a0uma mudan\u00e7a radical nos formatos dos pr\u00f3ximos leil\u00f5es de gera\u00e7\u00e3o de energia, dividindo em at\u00e9 tr\u00eas produtos diferentes o que hoje \u00e9 feito em uma \u00fanica contrata\u00e7\u00e3o. Primeiro, a ideia \u00e9 separar o lastro \u2013 capacidade total de produzir eletricidade, em MW\u00a0\u2013 do [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":3642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[1067,12,1226,1227,1225,96,71],"class_list":["post-3641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infraenergia","tag-empresa-de-pesquisa-energetica","tag-epe","tag-lastro-de-capacidade","tag-lastro-de-producao","tag-leiloes-de-geracao","tag-ministerio-de-minas-e-energia","tag-mme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v26.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro - Ag\u00eancia iNFRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro\" \/>\n<meta property=\"og:description\" content=\"Leila Coimbra,\u00a0da Ag\u00eancia iNFRA O MME (Minist\u00e9rio de Minas e Energia) vai propor\u00a0uma mudan\u00e7a radical nos formatos dos pr\u00f3ximos leil\u00f5es de gera\u00e7\u00e3o de energia, dividindo em at\u00e9 tr\u00eas produtos diferentes o que hoje \u00e9 feito em uma \u00fanica contrata\u00e7\u00e3o. Primeiro, a ideia \u00e9 separar o lastro \u2013 capacidade total de produzir eletricidade, em MW\u00a0\u2013 do [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/\" \/>\n<meta property=\"og:site_name\" content=\"Ag\u00eancia iNFRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ageninfra\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-28T11:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rodrigo Zuquim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@agencia_infra\" \/>\n<meta name=\"twitter:site\" content=\"@agencia_infra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rodrigo Zuquim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/\"},\"author\":{\"name\":\"Rodrigo Zuquim\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/04dbb79bd6d8951f063da71f3e4c1eb1\"},\"headline\":\"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro\",\"datePublished\":\"2019-08-28T11:00:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/\"},\"wordCount\":551,\"publisher\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg\",\"keywords\":[\"Empresa de Pesquisa Energ\u00e9tica\",\"epe\",\"lastro de capacidade\",\"lastro de produ\u00e7\u00e3o\",\"leil\u00f5es de gera\u00e7\u00e3o\",\"Minist\u00e9rio de Minas e Energia\",\"MME\"],\"articleSection\":[\"iNFRAEnergia\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/\",\"url\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/\",\"name\":\"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro - Ag\u00eancia iNFRA\",\"isPartOf\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg\",\"datePublished\":\"2019-08-28T11:00:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#primaryimage\",\"url\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg\",\"contentUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Foto: Saulo Cruz\/MME\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/agenciainfra.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#website\",\"url\":\"https:\/\/agenciainfra.com\/blog\/\",\"name\":\"Ag\u00eancia iNFRA\",\"description\":\"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!\",\"publisher\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agenciainfra.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\",\"name\":\"Ag\u00eancia iNFRA\",\"url\":\"https:\/\/agenciainfra.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png\",\"contentUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png\",\"width\":1672,\"height\":454,\"caption\":\"Ag\u00eancia iNFRA\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ageninfra\",\"https:\/\/x.com\/agencia_infra\",\"https:\/\/www.linkedin.com\/company\/ag\u00eanciainfra\/\",\"https:\/\/www.instagram.com\/agenciainfra\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/04dbb79bd6d8951f063da71f3e4c1eb1\",\"name\":\"Rodrigo Zuquim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/594abfe82761d620726242ff34ca472a705a4b97f16c790053a6b4c4035274d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/594abfe82761d620726242ff34ca472a705a4b97f16c790053a6b4c4035274d0?s=96&d=mm&r=g\",\"caption\":\"Rodrigo Zuquim\"},\"url\":\"https:\/\/agenciainfra.com\/blog\/author\/rodrigo-zuquim\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro - Ag\u00eancia iNFRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/","og_locale":"pt_BR","og_type":"article","og_title":"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro","og_description":"Leila Coimbra,\u00a0da Ag\u00eancia iNFRA O MME (Minist\u00e9rio de Minas e Energia) vai propor\u00a0uma mudan\u00e7a radical nos formatos dos pr\u00f3ximos leil\u00f5es de gera\u00e7\u00e3o de energia, dividindo em at\u00e9 tr\u00eas produtos diferentes o que hoje \u00e9 feito em uma \u00fanica contrata\u00e7\u00e3o. Primeiro, a ideia \u00e9 separar o lastro \u2013 capacidade total de produzir eletricidade, em MW\u00a0\u2013 do [&hellip;]","og_url":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/","og_site_name":"Ag\u00eancia iNFRA","article_publisher":"https:\/\/www.facebook.com\/ageninfra","article_published_time":"2019-08-28T11:00:58+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg","type":"image\/jpeg"}],"author":"Rodrigo Zuquim","twitter_card":"summary_large_image","twitter_creator":"@agencia_infra","twitter_site":"@agencia_infra","twitter_misc":{"Escrito por":"Rodrigo Zuquim","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#article","isPartOf":{"@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/"},"author":{"name":"Rodrigo Zuquim","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/04dbb79bd6d8951f063da71f3e4c1eb1"},"headline":"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro","datePublished":"2019-08-28T11:00:58+00:00","mainEntityOfPage":{"@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/"},"wordCount":551,"publisher":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#primaryimage"},"thumbnailUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg","keywords":["Empresa de Pesquisa Energ\u00e9tica","epe","lastro de capacidade","lastro de produ\u00e7\u00e3o","leil\u00f5es de gera\u00e7\u00e3o","Minist\u00e9rio de Minas e Energia","MME"],"articleSection":["iNFRAEnergia"],"inLanguage":"pt-BR","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/","url":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/","name":"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro - Ag\u00eancia iNFRA","isPartOf":{"@id":"https:\/\/agenciainfra.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#primaryimage"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#primaryimage"},"thumbnailUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg","datePublished":"2019-08-28T11:00:58+00:00","breadcrumb":{"@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#primaryimage","url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg","contentUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/sede-mme-foto-saulo-cruz-mme.jpg","width":1280,"height":853,"caption":"Foto: Saulo Cruz\/MME"},{"@type":"BreadcrumbList","@id":"https:\/\/agenciainfra.com\/blog\/governo-propoe-mudanca-nos-leiloes-de-geracao-separando-a-energia-do-lastro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/agenciainfra.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Governo prop\u00f5e mudan\u00e7a nos leil\u00f5es de gera\u00e7\u00e3o, separando a energia do lastro"}]},{"@type":"WebSite","@id":"https:\/\/agenciainfra.com\/blog\/#website","url":"https:\/\/agenciainfra.com\/blog\/","name":"Ag\u00eancia iNFRA","description":"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!","publisher":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agenciainfra.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/agenciainfra.com\/blog\/#organization","name":"Ag\u00eancia iNFRA","url":"https:\/\/agenciainfra.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","contentUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","width":1672,"height":454,"caption":"Ag\u00eancia iNFRA"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ageninfra","https:\/\/x.com\/agencia_infra","https:\/\/www.linkedin.com\/company\/ag\u00eanciainfra\/","https:\/\/www.instagram.com\/agenciainfra\/"]},{"@type":"Person","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/04dbb79bd6d8951f063da71f3e4c1eb1","name":"Rodrigo Zuquim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/594abfe82761d620726242ff34ca472a705a4b97f16c790053a6b4c4035274d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/594abfe82761d620726242ff34ca472a705a4b97f16c790053a6b4c4035274d0?s=96&d=mm&r=g","caption":"Rodrigo Zuquim"},"url":"https:\/\/agenciainfra.com\/blog\/author\/rodrigo-zuquim\/"}]}},"_links":{"self":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts\/3641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/comments?post=3641"}],"version-history":[{"count":0,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts\/3641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/media\/3642"}],"wp:attachment":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/media?parent=3641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/categories?post=3641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/tags?post=3641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}