{"id":41004,"date":"2026-05-13T10:30:00","date_gmt":"2026-05-13T13:30:00","guid":{"rendered":"https:\/\/agenciainfra.com\/blog\/?p=41004"},"modified":"2026-05-13T11:59:41","modified_gmt":"2026-05-13T14:59:41","slug":"petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp","status":"publish","type":"post","link":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/","title":{"rendered":"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP"},"content":{"rendered":"\n<p class=\"has-text-align-right\"><strong>Gabriel Vasconcelos, Marisa Wanzeller e Lais Carregosa, da Ag\u00eancia iNFRA<\/strong><\/p>\n\n\n\n<p>A Petrobras sinalizou na ter\u00e7a-feira (12) para um aumento no pre\u00e7o da gasolina produzida em suas refinarias em breve. A presidente da companhia, Magda Chambriard, disse que a alta deve acontecer \u201cj\u00e1 j\u00e1\u201d, mas que a estatal tenta preservar o mercado para o combust\u00edvel frente \u00e0 queda nos valores do etanol hidratado, que concorre com a gasolina. A <a href=\"https:\/\/agenciainfra.com\/blog\/magda-gasolina-vai-aumentar-ja-ja-diesel-segue-politica-de-precos\/\">manifesta\u00e7\u00e3o<\/a> ocorreu em teleconfer\u00eancia com investidores para apresenta\u00e7\u00e3o de resultados da companhia.<br><br>A presidente da companhia j\u00e1 sinalizou anteriormente que a aprova\u00e7\u00e3o do\u00a0<a href=\"https:\/\/us.list-manage.com\/mtCLRWWXT_L?e=55b7a27fc9&amp;c2id=e9dfbcda5f02bd2f0f32ef4cdb38a4c7\" target=\"_blank\" rel=\"noreferrer noopener\">PLP \u00a0(Projeto de Lei Complementar) 114\/2026<\/a>\u00a0\u2013 que trata do uso de receitas do petr\u00f3leo para zerar tributos da gasolina \u2013 daria espa\u00e7o para que o reajuste ocorresse sem pesar para as distribuidoras. A tramita\u00e7\u00e3o do projeto aguardada para esta semana, no entanto, foi adiada para a pr\u00f3xima, conforme disseram fontes \u00e0\u00a0<strong>Ag\u00eancia iNFRA<\/strong>.<br><br>Na ter\u00e7a, a diretora executiva de Transi\u00e7\u00e3o Energ\u00e9tica e diretora interina de Log\u00edstica, Ang\u00e9lica Laureano, disse que a pol\u00edtica de comercializa\u00e7\u00e3o da estatal \u201cest\u00e1 dissociada\u201d do projeto e trata da \u201can\u00e1lise de pre\u00e7os internos, de importados, volume de produ\u00e7\u00e3o interna\u201d, entre outros pontos. \u201cHoje, estamos equilibrados nisso. Se avaliarmos que estamos persistentemente com o pre\u00e7o que n\u00e3o atende \u00e0 nossa expectativa, a gente vai aumentar, e talvez o PLP venha para ajudar a n\u00e3o repassar isso para o mercado\u201d, disse \u00e0 imprensa.<br><br>Enquanto a Petrobras \u00e9 pressionada pela defasagem entre os pre\u00e7os praticados pela estatal e os valores internacionais, o governo busca formas de evitar o repasse integral para a popula\u00e7\u00e3o. O projeto \u00e9 a aposta inicial para diluir parte do impacto ao consumidor.<br><br>Na segunda-feira (11), Magda se reuniu com o ministro da Fazenda, Dario Durigan, em Bras\u00edlia. Ap\u00f3s o encontro, questionado sobre a falta de reajustes da Petrobras, Durigan disse ter sentido que \u201ch\u00e1 uma necessidade da Petrobras de ir reavaliando esses pre\u00e7os\u201d. O ministro enfatizou que, para al\u00e9m de a Petrobras cumprir a sua pol\u00edtica de pre\u00e7os, \u00e9 preciso, do lado do governo, adotar medidas adicionais para evitar a alta aos consumidores.<br><br>Dados da Abicom (Associa\u00e7\u00e3o Brasileira dos Importadores de Combust\u00edveis) da ter\u00e7a-feira (12)\u00a0<a href=\"https:\/\/us.list-manage.com\/5guS8rJgkAY?e=55b7a27fc9&amp;c2id=e9dfbcda5f02bd2f0f32ef4cdb38a4c7\" target=\"_blank\" rel=\"noreferrer noopener\">apontam<\/a>\u00a0para uma defasagem m\u00e9dia de 81% no pre\u00e7o da gasolina nos polos da Petrobras, na compara\u00e7\u00e3o entre pre\u00e7os internos e internacionais. Segundo a associa\u00e7\u00e3o, isso significa que os pre\u00e7os est\u00e3o R$ 2,03 por litro abaixo do PPI (Pre\u00e7o de Paridade de Importa\u00e7\u00e3o).<br><br><strong>Tramita\u00e7\u00e3o do PLP<\/strong><br>Durigan disse a jornalistas que informou \u00e0 Magda sobre a tramita\u00e7\u00e3o do projeto e a expectativa do governo de aprovar o texto no plen\u00e1rio da C\u00e2mara ainda nesta semana. No entanto, o PLP est\u00e1 em compasso de espera no momento, enquanto a relatora, deputada Marussa Boldrin (Republicanos-GO), est\u00e1 em evento nos Estados Unidos.\u00a0<br><br>Segundo fontes, as negocia\u00e7\u00f5es em torno do texto devem ocorrer somente na pr\u00f3xima semana. Interlocutores do governo apontam que a relatora teria desistido de altera\u00e7\u00f5es que atenderiam ao agroneg\u00f3cio, mas que manteria o diferencial competitivo para os biocombust\u00edveis, com apoio da ala econ\u00f4mica do Planalto.\u00a0<br><br><strong>Altera\u00e7\u00f5es<\/strong><br>Marussa, que integra a FPA (Frente Parlamentar da Agropecu\u00e1ria), disse \u00e0 imprensa na \u00faltima semana que pretendia <a href=\"https:\/\/agenciainfra.com\/blog\/plp-da-gasolina-relatora-pede-que-receita-do-petroleo-atenda-ao-agro\/\">alterar o texto<\/a> do projeto para incluir temas caros \u00e0 bancada. Al\u00e9m de um instrumento para garantir vantagem competitiva aos biocombust\u00edveis (etanol e biodiesel), a relatora pretendia acrescentar previs\u00e3o para que parte do dinheiro da arrecada\u00e7\u00e3o com o petr\u00f3leo fosse destinado \u00e0 quita\u00e7\u00e3o de d\u00edvidas do agroneg\u00f3cio. O montante poderia ser fixado em no m\u00ednimo R$ 20 bilh\u00f5es.\u00a0<br><br>O governo, no entanto, se posicionou contra essas altera\u00e7\u00f5es. O ministro da Fazenda <a href=\"https:\/\/agenciainfra.com\/blog\/governo-espera-aprovacao-do-plp-da-gasolina-nesta-semana-diz-durigan\/\">disse \u00e0 imprensa<\/a> que \u201cn\u00e3o \u00e9 momento de ampliar o escopo\u201d do projeto. De acordo com ele, o texto \u00e9 urgente e deve ser aprovado o mais r\u00e1pido poss\u00edvel, \u201csem preju\u00edzo de outras discuss\u00f5es que podem seguir em paralelo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gabriel Vasconcelos, Marisa Wanzeller e Lais Carregosa, da Ag\u00eancia iNFRA A Petrobras sinalizou na ter\u00e7a-feira (12) para um aumento no pre\u00e7o da gasolina produzida em suas refinarias em breve. A presidente da companhia, Magda Chambriard, disse que a alta deve acontecer \u201cj\u00e1 j\u00e1\u201d, mas que a estatal tenta preservar o mercado para o combust\u00edvel frente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":41007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7249],"tags":[2474,314,14528,315,13251,3365,13132,9446,7366,19631,3191,143,19578,13597],"class_list":["post-41004","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","tag-biocombustiveis","tag-combustiveis","tag-dario-durigan","tag-diesel","tag-gabriel-vasconcelos","tag-gasolina","tag-lais-carregosa","tag-magda-chambriard","tag-marisa-wanzeller","tag-marussa-boldrin","tag-oleo-e-gas","tag-petrobras","tag-plp-114-2026","tag-preco-da-gasolina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v26.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP - Ag\u00eancia iNFRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP\" \/>\n<meta property=\"og:description\" content=\"Gabriel Vasconcelos, Marisa Wanzeller e Lais Carregosa, da Ag\u00eancia iNFRA A Petrobras sinalizou na ter\u00e7a-feira (12) para um aumento no pre\u00e7o da gasolina produzida em suas refinarias em breve. A presidente da companhia, Magda Chambriard, disse que a alta deve acontecer \u201cj\u00e1 j\u00e1\u201d, mas que a estatal tenta preservar o mercado para o combust\u00edvel frente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/\" \/>\n<meta property=\"og:site_name\" content=\"Ag\u00eancia iNFRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ageninfra\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T13:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T14:59:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ag\u00eancia iNFRA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@agencia_infra\" \/>\n<meta name=\"twitter:site\" content=\"@agencia_infra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ag\u00eancia iNFRA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/\"},\"author\":{\"name\":\"Ag\u00eancia iNFRA\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/34af08dff6adea4cb22b06612ba7acfa\"},\"headline\":\"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP\",\"datePublished\":\"2026-05-13T13:30:00+00:00\",\"dateModified\":\"2026-05-13T14:59:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/\"},\"wordCount\":685,\"publisher\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg\",\"keywords\":[\"biocombust\u00edveis\",\"combust\u00edveis\",\"Dario Durigan\",\"diesel\",\"Gabriel Vasconcelos\",\"gasolina\",\"Lais Carregosa\",\"Magda Chambriard\",\"Marisa Wanzeller\",\"Marussa Boldrin\",\"\u00f3leo e g\u00e1s\",\"Petrobras\",\"PLP 114\/2026\",\"pre\u00e7o da gasolina\"],\"articleSection\":[\"Destaque\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/\",\"url\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/\",\"name\":\"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP - Ag\u00eancia iNFRA\",\"isPartOf\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg\",\"datePublished\":\"2026-05-13T13:30:00+00:00\",\"dateModified\":\"2026-05-13T14:59:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#primaryimage\",\"url\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg\",\"contentUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Foto: Fernando Fraz\u00e3o\/Ag\u00eancia Brasil\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/agenciainfra.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#website\",\"url\":\"https:\/\/agenciainfra.com\/blog\/\",\"name\":\"Ag\u00eancia iNFRA\",\"description\":\"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!\",\"publisher\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agenciainfra.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\",\"name\":\"Ag\u00eancia iNFRA\",\"url\":\"https:\/\/agenciainfra.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png\",\"contentUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png\",\"width\":1672,\"height\":454,\"caption\":\"Ag\u00eancia iNFRA\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ageninfra\",\"https:\/\/x.com\/agencia_infra\",\"https:\/\/www.linkedin.com\/company\/ag\u00eanciainfra\/\",\"https:\/\/www.instagram.com\/agenciainfra\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/34af08dff6adea4cb22b06612ba7acfa\",\"name\":\"Ag\u00eancia iNFRA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d189e01678f06d8eb84d4e01f08eb848b3fffe3f8443818d3c356c66892f5be8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d189e01678f06d8eb84d4e01f08eb848b3fffe3f8443818d3c356c66892f5be8?s=96&d=mm&r=g\",\"caption\":\"Ag\u00eancia iNFRA\"},\"url\":\"https:\/\/agenciainfra.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP - Ag\u00eancia iNFRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/","og_locale":"pt_BR","og_type":"article","og_title":"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP","og_description":"Gabriel Vasconcelos, Marisa Wanzeller e Lais Carregosa, da Ag\u00eancia iNFRA A Petrobras sinalizou na ter\u00e7a-feira (12) para um aumento no pre\u00e7o da gasolina produzida em suas refinarias em breve. A presidente da companhia, Magda Chambriard, disse que a alta deve acontecer \u201cj\u00e1 j\u00e1\u201d, mas que a estatal tenta preservar o mercado para o combust\u00edvel frente [&hellip;]","og_url":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/","og_site_name":"Ag\u00eancia iNFRA","article_publisher":"https:\/\/www.facebook.com\/ageninfra","article_published_time":"2026-05-13T13:30:00+00:00","article_modified_time":"2026-05-13T14:59:41+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg","type":"image\/jpeg"}],"author":"Ag\u00eancia iNFRA","twitter_card":"summary_large_image","twitter_creator":"@agencia_infra","twitter_site":"@agencia_infra","twitter_misc":{"Escrito por":"Ag\u00eancia iNFRA","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#article","isPartOf":{"@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/"},"author":{"name":"Ag\u00eancia iNFRA","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/34af08dff6adea4cb22b06612ba7acfa"},"headline":"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP","datePublished":"2026-05-13T13:30:00+00:00","dateModified":"2026-05-13T14:59:41+00:00","mainEntityOfPage":{"@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/"},"wordCount":685,"publisher":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#primaryimage"},"thumbnailUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg","keywords":["biocombust\u00edveis","combust\u00edveis","Dario Durigan","diesel","Gabriel Vasconcelos","gasolina","Lais Carregosa","Magda Chambriard","Marisa Wanzeller","Marussa Boldrin","\u00f3leo e g\u00e1s","Petrobras","PLP 114\/2026","pre\u00e7o da gasolina"],"articleSection":["Destaque"],"inLanguage":"pt-BR","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/","url":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/","name":"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP - Ag\u00eancia iNFRA","isPartOf":{"@id":"https:\/\/agenciainfra.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#primaryimage"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#primaryimage"},"thumbnailUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg","datePublished":"2026-05-13T13:30:00+00:00","dateModified":"2026-05-13T14:59:41+00:00","breadcrumb":{"@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#primaryimage","url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg","contentUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2026\/05\/magda-chambriard_foto_fernando-frazao-agencia_brasil.jpg","width":1280,"height":853,"caption":"Foto: Fernando Fraz\u00e3o\/Ag\u00eancia Brasil"},{"@type":"BreadcrumbList","@id":"https:\/\/agenciainfra.com\/blog\/petrobras-pode-reajustar-gasolina-mesmo-sem-aprovacao-de-plp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/agenciainfra.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Petrobras pode reajustar gasolina mesmo sem aprova\u00e7\u00e3o de PLP"}]},{"@type":"WebSite","@id":"https:\/\/agenciainfra.com\/blog\/#website","url":"https:\/\/agenciainfra.com\/blog\/","name":"Ag\u00eancia iNFRA","description":"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!","publisher":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agenciainfra.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/agenciainfra.com\/blog\/#organization","name":"Ag\u00eancia iNFRA","url":"https:\/\/agenciainfra.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","contentUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","width":1672,"height":454,"caption":"Ag\u00eancia iNFRA"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ageninfra","https:\/\/x.com\/agencia_infra","https:\/\/www.linkedin.com\/company\/ag\u00eanciainfra\/","https:\/\/www.instagram.com\/agenciainfra\/"]},{"@type":"Person","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/34af08dff6adea4cb22b06612ba7acfa","name":"Ag\u00eancia iNFRA","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d189e01678f06d8eb84d4e01f08eb848b3fffe3f8443818d3c356c66892f5be8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d189e01678f06d8eb84d4e01f08eb848b3fffe3f8443818d3c356c66892f5be8?s=96&d=mm&r=g","caption":"Ag\u00eancia iNFRA"},"url":"https:\/\/agenciainfra.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts\/41004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/comments?post=41004"}],"version-history":[{"count":2,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts\/41004\/revisions"}],"predecessor-version":[{"id":41009,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts\/41004\/revisions\/41009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/media\/41007"}],"wp:attachment":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/media?parent=41004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/categories?post=41004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/tags?post=41004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}