{"id":5362,"date":"2020-07-10T08:00:00","date_gmt":"2020-07-10T11:00:00","guid":{"rendered":"https:\/\/www.agenciainfra.com\/blog\/?p=5362"},"modified":"2020-07-09T11:28:50","modified_gmt":"2020-07-09T14:28:50","slug":"tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid","status":"publish","type":"post","link":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/","title":{"rendered":"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-text-align-right\"><strong>Guilherme Mendes e Leila Coimbra,&nbsp;da Ag\u00eancia iNFRA<\/strong><\/p>\n\n\n\n<p>O TCU (Tribunal de Contas da Uni\u00e3o) apontou como positiva a decis\u00e3o da ANEEL (Ag\u00eancia Nacional de Energia El\u00e9trica) de n\u00e3o incluir o reequil\u00edbrio econ\u00f4mico-financeiro dos contratos de concess\u00e3o das distribuidoras el\u00e9tricas na resolu\u00e7\u00e3o 885\/2020, que normatiza a &#8220;Conta-Covid&#8221;. A conclus\u00e3o est\u00e1 em um\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/agenciainfra.us14.list-manage.com\/track\/click?u=d460dd1bcf9ba0ae040e1fc0f&amp;id=f012c13373&amp;e=c099169394\" target=\"_blank\">relat\u00f3rio preliminar<\/a>\u00a0do tribunal sobre a opera\u00e7\u00e3o de empr\u00e9stimo, datado da \u00faltima ter\u00e7a-feira (7).<br><br>Segundo os tr\u00eas t\u00e9cnicos do TCU que assinam o texto, &#8220;a solu\u00e7\u00e3o final dada pela ANEEL \u00e9 adequada ao n\u00e3o reconhecer de maneira abstrata e geral o direito objetivo das distribuidoras ao reequil\u00edbrio dos contratos, mas apenas o direito subjetivo de solicitarem esse reequil\u00edbrio e de terem seu pedido analisado pela ag\u00eancia&#8221;.<br><br>Desta forma, a inten\u00e7\u00e3o da ag\u00eancia de regular os aspectos econ\u00f4micos em um momento futuro\u00a0seria, na vis\u00e3o do tribunal, &#8220;justamente para ter uma metodologia clara e padronizada quanto aos efeitos da pandemia, trazendo seguran\u00e7a e uniformidade aos casos concretos que surjam&#8221;.<br><br><strong>Desequil\u00edbrio versus lucros e dividendos<\/strong><br>Os autores do estudo\u00a0consideram essencial que a ANEEL exija a comprova\u00e7\u00e3o do desequil\u00edbrio financeiro das distribuidoras, sob risco de que ocorram discrep\u00e2ncias no futuro: &#8220;N\u00e3o seria plaus\u00edvel que determinada empresa alegasse desequil\u00edbrio econ\u00f4mico-financeiro decorrente de onerosidade excessiva e ao mesmo tempo apresentasse lucro l\u00edquido, pagando Juros sobre o Capital Pr\u00f3prio (JSCP) e\/ou distribuindo dividendos acima do limite legal&#8221;, afirmam.<br><br>O documento tamb\u00e9m apresenta um panorama das discuss\u00f5es sobre a antecipa\u00e7\u00e3o da Parcela B dos processos de RTE (Revis\u00e3o Tarif\u00e1ria Extraordin\u00e1ria) das distribuidoras privatizadas.<br><br>O tema causou controv\u00e9rsia entre os diretores da ANEEL durante a formula\u00e7\u00e3o da\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/agenciainfra.us14.list-manage.com\/track\/click?u=d460dd1bcf9ba0ae040e1fc0f&amp;id=43f73edac1&amp;e=c099169394\" target=\"_blank\">Resolu\u00e7\u00e3o 885<\/a>\u00a0e culminou com a ag\u00eancia n\u00e3o incluindo no texto final o\u00a0diferimento de revis\u00f5es tarif\u00e1rias ainda n\u00e3o deliberadas. O argumento que prevaleceu era de que a\u00a0mitiga\u00e7\u00e3o de aumentos tarif\u00e1rios, decorrentes de eventuais problemas passados ou presentes das concess\u00f5es, deve ser tratada pelo MME (Minist\u00e9rio de Minas e Energia).<br><br>Neste ponto, os autores\u00a0cobram que o Executivo se posicione frente a problemas que ele pode melhor ajustar e endere\u00e7ar, com isso &#8220;tirando peso desnecess\u00e1rio da ag\u00eancia reguladora, que tem a compet\u00eancia de operacionalizar as pol\u00edticas, possibilitando, dessa maneira, que ela atue de maneira t\u00e9cnica e objetiva, obedecendo seu mandato&#8221;.<br><br><strong>Mecanismos de descontrata\u00e7\u00e3o s\u00e3o &#8220;primordiais&#8221;<\/strong><br>Os auditores se mostraram favor\u00e1veis \u00e0\u00a0proposta da ANEEL de permitir que a CCEE (C\u00e2mara de Comercializa\u00e7\u00e3o de Energia El\u00e9trica) realize o processamento extraordin\u00e1rio do MCSDEN (Mecanismo de Compensa\u00e7\u00e3o de Sobras e D\u00e9ficits de Energia Nova A-1) e do MVE (Mecanismo de Vendas de Excedentes Anual) de 2021 entre os meses de junho e agosto deste ano. A medida extraordin\u00e1ria, aprovada no m\u00eas passado, adianta a venda de excedentes surgidos pela queda de demanda na pandemia.<br><br>&#8220;A conclus\u00e3o e operacionaliza\u00e7\u00e3o desses mecanismos de gest\u00e3o de portf\u00f3lio dos contratos das distribuidoras ser\u00e1 primordial para o tratamento dos problemas econ\u00f4micos vivenciados pelas empresas de distribui\u00e7\u00e3o&#8221;, escreve a \u00e1rea t\u00e9cnica do TCU, &#8220;possibilitando que parte da sobrecontrata\u00e7\u00e3o generalizada atualmente existente seja reduzida&#8221;.\u00a0<br><br>O tribunal de contas ressaltou que a entrada nos procedimentos extraordin\u00e1rios \u00e9 optativa a cada distribuidora. Os geradores fariam propostas de produtos \u2013 tais como quantidade de meses para diferimento, car\u00eancia para in\u00edcio do pagamento, prazo para quita\u00e7\u00e3o dos valores diferidos e taxa de remunera\u00e7\u00e3o \u2013 para, em seguida, as distribuidoras que tiverem contratos com esses geradores e se interessarem poderem aderir \u00e0 oferta.<br><br>A ag\u00eancia manteve consulta p\u00fablica aberta at\u00e9 o dia 1\u00ba deste m\u00eas para o aprimoramento do cronograma de realiza\u00e7\u00e3o do MCSDEN e MVE, bem como sobre a proposta de desenvolvimento de novo mecanismo para o diferimento total e\/ou parcial de receitas fixas.<br><br><strong>Pol\u00edtica de cortes de energia<\/strong><br>O TCU tamb\u00e9m dedicou parte do relat\u00f3rio a destrinchar a\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/agenciainfra.us14.list-manage.com\/track\/click?u=d460dd1bcf9ba0ae040e1fc0f&amp;id=59389b9b62&amp;e=c099169394\" target=\"_blank\">resolu\u00e7\u00e3o normativa 878 da ANEEL<\/a>, que entre outros t\u00f3picos impede a suspens\u00e3o do corte de energia el\u00e9trica de consumidores inadimplentes, por conta da pandemia. No m\u00eas passado, atendendo a um pedido dos estados, a ag\u00eancia prorrogou de 60 para 90 dias a suspens\u00e3o, v\u00e1lida\u00a0at\u00e9 o final de julho.<br><br>Ao tratar da quest\u00e3o, a \u00e1rea t\u00e9cnica do TCU afirma que, embora a extens\u00e3o do prazo de suspens\u00e3o de cortes proteja os consumidores residenciais e funcion\u00e1rios das distribuidoras, a medida prejudica ainda mais o caixa das distribuidoras, ao se prolongar o per\u00edodo no qual as empresas n\u00e3o podem se utilizar de um dos mecanismos mais eficientes para combate \u00e0 inadimpl\u00eancia, a suspens\u00e3o de fornecimento.<br><br>Com isso, o estudo conclui ser essencial o acompanhamento da evolu\u00e7\u00e3o de indicadores de inadimpl\u00eancia, dado que \u00e9 esperado que haja recupera\u00e7\u00e3o desses valores \u00e0 medida que a crise se abrande \u2013 mesmo que ainda n\u00e3o haja um horizonte claro. &#8220;Isso porque n\u00e3o \u00e9 tarefa trivial estimar a velocidade dessa recupera\u00e7\u00e3o e\/ou os valores que ser\u00e3o considerados irrecuper\u00e1veis pelo regulador e se tornar\u00e3o pass\u00edveis de inclus\u00e3o na tarifa&#8221;, defendem os auditores.<br><br><strong>Condi\u00e7\u00f5es do empr\u00e9stimo<\/strong><br>O tribunal tamb\u00e9m recomenda uma avalia\u00e7\u00e3o detalhada da ag\u00eancia reguladora e das distribuidoras para as condi\u00e7\u00f5es da opera\u00e7\u00e3o de empr\u00e9stimo \u2013 que seriam mais onerosas que repasses negociados de maneira individualizadas. &#8220;Isso se deve ao fato de que terceiro alheio \u00e0 opera\u00e7\u00e3o (o consumidor) arcar\u00e1 com parte significativa desses custos&#8221;, concluem os autores do estudo.<br><br>No dia 3 de julho, a\u00a0<strong>Ag\u00eancia iNFRA<\/strong>\u00a0publicou mat\u00e9ria informando\u00a0que, mesmo durante a pandemia do novo coronav\u00edrus, empresas negociaram empr\u00e9stimos do BNDES (Banco Nacional de Desenvolvimento Econ\u00f4mico e Social) em<a rel=\"noreferrer noopener\" href=\"https:\/\/agenciainfra.us14.list-manage.com\/track\/click?u=d460dd1bcf9ba0ae040e1fc0f&amp;id=6369565dbc&amp;e=c099169394\" target=\"_blank\">\u00a0condi\u00e7\u00f5es mais favor\u00e1veis<\/a>\u00a0que as previstas na Conta-Covid.\u00a0No dia 6 de julho, o diretor da ANEEL, Andr\u00e9 Pepitone, afirmou que\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/agenciainfra.us14.list-manage.com\/track\/click?u=d460dd1bcf9ba0ae040e1fc0f&amp;id=d4e27c47cc&amp;e=c099169394\" target=\"_blank\">a compara\u00e7\u00e3o n\u00e3o seria v\u00e1lida<\/a>, j\u00e1 que a Conta-Covid tem como objetivo dar capital de giro ao caixa das empresas, e n\u00e3o \u00e9 destinada a investimentos espec\u00edficos.<br><br>A resolu\u00e7\u00e3o determina que a ANEEL inicie a discuss\u00e3o sobre o reequil\u00edbrio se valendo de consulta p\u00fablica, a ser aberta at\u00e9 60 dias ap\u00f3s a publica\u00e7\u00e3o do texto normativo \u2013 ocorrida h\u00e1 16 dias. O relat\u00f3rio, preliminar, ainda n\u00e3o prop\u00f5e ou encaminha a\u00e7\u00f5es ao Poder Executivo.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guilherme Mendes e Leila Coimbra,&nbsp;da Ag\u00eancia iNFRA O TCU (Tribunal de Contas da Uni\u00e3o) apontou como positiva a decis\u00e3o da ANEEL (Ag\u00eancia Nacional de Energia El\u00e9trica) de n\u00e3o incluir o reequil\u00edbrio econ\u00f4mico-financeiro dos contratos de concess\u00e3o das distribuidoras el\u00e9tricas na resolu\u00e7\u00e3o 885\/2020, que normatiza a &#8220;Conta-Covid&#8221;. A conclus\u00e3o est\u00e1 em um\u00a0relat\u00f3rio preliminar\u00a0do tribunal sobre a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":3613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1,10],"tags":[820,53,103,14,1949,292,96,1938,2252,18],"class_list":["post-5362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-infraenergia","tag-andre-pepitone","tag-aneel","tag-bndes","tag-ccee","tag-conta-covid","tag-distribuidoras","tag-ministerio-de-minas-e-energia","tag-reequilibrio","tag-resolucao-885","tag-tcu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v26.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid - Ag\u00eancia iNFRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid\" \/>\n<meta property=\"og:description\" content=\"Guilherme Mendes e Leila Coimbra,&nbsp;da Ag\u00eancia iNFRA O TCU (Tribunal de Contas da Uni\u00e3o) apontou como positiva a decis\u00e3o da ANEEL (Ag\u00eancia Nacional de Energia El\u00e9trica) de n\u00e3o incluir o reequil\u00edbrio econ\u00f4mico-financeiro dos contratos de concess\u00e3o das distribuidoras el\u00e9tricas na resolu\u00e7\u00e3o 885\/2020, que normatiza a &#8220;Conta-Covid&#8221;. A conclus\u00e3o est\u00e1 em um\u00a0relat\u00f3rio preliminar\u00a0do tribunal sobre a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/\" \/>\n<meta property=\"og:site_name\" content=\"Ag\u00eancia iNFRA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ageninfra\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rodrigo Zuquim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@agencia_infra\" \/>\n<meta name=\"twitter:site\" content=\"@agencia_infra\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rodrigo Zuquim\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/\"},\"author\":{\"name\":\"Rodrigo Zuquim\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/04dbb79bd6d8951f063da71f3e4c1eb1\"},\"headline\":\"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid\",\"datePublished\":\"2020-07-10T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/\"},\"wordCount\":1120,\"publisher\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg\",\"keywords\":[\"Andr\u00e9 Pepitone\",\"ANEEL\",\"BNDES\",\"ccee\",\"Conta-Covid\",\"distribuidoras\",\"Minist\u00e9rio de Minas e Energia\",\"reequil\u00edbrio\",\"Resolu\u00e7\u00e3o 885\",\"TCU\"],\"articleSection\":[\"Geral\",\"iNFRAEnergia\"],\"inLanguage\":\"pt-BR\",\"copyrightYear\":\"2020\",\"copyrightHolder\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/\",\"url\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/\",\"name\":\"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid - Ag\u00eancia iNFRA\",\"isPartOf\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg\",\"datePublished\":\"2020-07-10T11:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#primaryimage\",\"url\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg\",\"contentUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg\",\"width\":1280,\"height\":854},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/agenciainfra.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#website\",\"url\":\"https:\/\/agenciainfra.com\/blog\/\",\"name\":\"Ag\u00eancia iNFRA\",\"description\":\"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!\",\"publisher\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/agenciainfra.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#organization\",\"name\":\"Ag\u00eancia iNFRA\",\"url\":\"https:\/\/agenciainfra.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png\",\"contentUrl\":\"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png\",\"width\":1672,\"height\":454,\"caption\":\"Ag\u00eancia iNFRA\"},\"image\":{\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ageninfra\",\"https:\/\/x.com\/agencia_infra\",\"https:\/\/www.linkedin.com\/company\/ag\u00eanciainfra\/\",\"https:\/\/www.instagram.com\/agenciainfra\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/04dbb79bd6d8951f063da71f3e4c1eb1\",\"name\":\"Rodrigo Zuquim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/594abfe82761d620726242ff34ca472a705a4b97f16c790053a6b4c4035274d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/594abfe82761d620726242ff34ca472a705a4b97f16c790053a6b4c4035274d0?s=96&d=mm&r=g\",\"caption\":\"Rodrigo Zuquim\"},\"url\":\"https:\/\/agenciainfra.com\/blog\/author\/rodrigo-zuquim\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid - Ag\u00eancia iNFRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/","og_locale":"pt_BR","og_type":"article","og_title":"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid","og_description":"Guilherme Mendes e Leila Coimbra,&nbsp;da Ag\u00eancia iNFRA O TCU (Tribunal de Contas da Uni\u00e3o) apontou como positiva a decis\u00e3o da ANEEL (Ag\u00eancia Nacional de Energia El\u00e9trica) de n\u00e3o incluir o reequil\u00edbrio econ\u00f4mico-financeiro dos contratos de concess\u00e3o das distribuidoras el\u00e9tricas na resolu\u00e7\u00e3o 885\/2020, que normatiza a &#8220;Conta-Covid&#8221;. A conclus\u00e3o est\u00e1 em um\u00a0relat\u00f3rio preliminar\u00a0do tribunal sobre a [&hellip;]","og_url":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/","og_site_name":"Ag\u00eancia iNFRA","article_publisher":"https:\/\/www.facebook.com\/ageninfra","article_published_time":"2020-07-10T11:00:00+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg","type":"image\/jpeg"}],"author":"Rodrigo Zuquim","twitter_card":"summary_large_image","twitter_creator":"@agencia_infra","twitter_site":"@agencia_infra","twitter_misc":{"Escrito por":"Rodrigo Zuquim","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#article","isPartOf":{"@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/"},"author":{"name":"Rodrigo Zuquim","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/04dbb79bd6d8951f063da71f3e4c1eb1"},"headline":"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid","datePublished":"2020-07-10T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/"},"wordCount":1120,"publisher":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg","keywords":["Andr\u00e9 Pepitone","ANEEL","BNDES","ccee","Conta-Covid","distribuidoras","Minist\u00e9rio de Minas e Energia","reequil\u00edbrio","Resolu\u00e7\u00e3o 885","TCU"],"articleSection":["Geral","iNFRAEnergia"],"inLanguage":"pt-BR","copyrightYear":"2020","copyrightHolder":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/","url":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/","name":"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid - Ag\u00eancia iNFRA","isPartOf":{"@id":"https:\/\/agenciainfra.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#primaryimage"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#primaryimage"},"thumbnailUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg","datePublished":"2020-07-10T11:00:00+00:00","breadcrumb":{"@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#primaryimage","url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg","contentUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2019\/08\/TCU-sede-foto-evelynne-gubert-tcu.jpg","width":1280,"height":854},{"@type":"BreadcrumbList","@id":"https:\/\/agenciainfra.com\/blog\/tcu-elogia-aneel-por-nao-incluir-reequilibrio-de-contratos-de-distribuidoras-em-conta-covid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/agenciainfra.com\/blog\/"},{"@type":"ListItem","position":2,"name":"TCU elogia ANEEL por n\u00e3o incluir reequil\u00edbrio de contratos de distribuidoras em Conta-Covid"}]},{"@type":"WebSite","@id":"https:\/\/agenciainfra.com\/blog\/#website","url":"https:\/\/agenciainfra.com\/blog\/","name":"Ag\u00eancia iNFRA","description":"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!","publisher":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agenciainfra.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/agenciainfra.com\/blog\/#organization","name":"Ag\u00eancia iNFRA","url":"https:\/\/agenciainfra.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","contentUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","width":1672,"height":454,"caption":"Ag\u00eancia iNFRA"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ageninfra","https:\/\/x.com\/agencia_infra","https:\/\/www.linkedin.com\/company\/ag\u00eanciainfra\/","https:\/\/www.instagram.com\/agenciainfra\/"]},{"@type":"Person","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/04dbb79bd6d8951f063da71f3e4c1eb1","name":"Rodrigo Zuquim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/594abfe82761d620726242ff34ca472a705a4b97f16c790053a6b4c4035274d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/594abfe82761d620726242ff34ca472a705a4b97f16c790053a6b4c4035274d0?s=96&d=mm&r=g","caption":"Rodrigo Zuquim"},"url":"https:\/\/agenciainfra.com\/blog\/author\/rodrigo-zuquim\/"}]}},"_links":{"self":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts\/5362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/comments?post=5362"}],"version-history":[{"count":0,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts\/5362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/media\/3613"}],"wp:attachment":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/media?parent=5362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/categories?post=5362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/tags?post=5362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}