{"id":20049,"count":1,"description":"","link":"https:\/\/agenciainfra.com\/blog\/tag\/relatorio-de-sustentabilidade\/","name":"relat\u00f3rio de sustentabilidade","slug":"relatorio-de-sustentabilidade","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arquivos relat\u00f3rio de sustentabilidade - Ag\u00eancia iNFRA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agenciainfra.com\/blog\/tag\/relatorio-de-sustentabilidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos relat\u00f3rio de sustentabilidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agenciainfra.com\/blog\/tag\/relatorio-de-sustentabilidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Ag\u00eancia iNFRA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@agencia_infra\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/tag\\\/relatorio-de-sustentabilidade\\\/\",\"url\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/tag\\\/relatorio-de-sustentabilidade\\\/\",\"name\":\"Arquivos relat\u00f3rio de sustentabilidade - Ag\u00eancia iNFRA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/tag\\\/relatorio-de-sustentabilidade\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/tag\\\/relatorio-de-sustentabilidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"relat\u00f3rio de sustentabilidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/\",\"name\":\"Ag\u00eancia iNFRA\",\"description\":\"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!\",\"publisher\":{\"@id\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/#organization\",\"name\":\"Ag\u00eancia iNFRA\",\"url\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/iNFRA_5-e1761735885940.png\",\"contentUrl\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/iNFRA_5-e1761735885940.png\",\"width\":1672,\"height\":454,\"caption\":\"Ag\u00eancia iNFRA\"},\"image\":{\"@id\":\"https:\\\/\\\/agenciainfra.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ageninfra\",\"https:\\\/\\\/x.com\\\/agencia_infra\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/ag\u00eanciainfra\\\/\",\"https:\\\/\\\/www.instagram.com\\\/agenciainfra\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arquivos relat\u00f3rio de sustentabilidade - Ag\u00eancia iNFRA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agenciainfra.com\/blog\/tag\/relatorio-de-sustentabilidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos relat\u00f3rio de sustentabilidade","og_url":"https:\/\/agenciainfra.com\/blog\/tag\/relatorio-de-sustentabilidade\/","og_site_name":"Ag\u00eancia iNFRA","twitter_card":"summary_large_image","twitter_site":"@agencia_infra","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/agenciainfra.com\/blog\/tag\/relatorio-de-sustentabilidade\/","url":"https:\/\/agenciainfra.com\/blog\/tag\/relatorio-de-sustentabilidade\/","name":"Arquivos relat\u00f3rio de sustentabilidade - Ag\u00eancia iNFRA","isPartOf":{"@id":"https:\/\/agenciainfra.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/agenciainfra.com\/blog\/tag\/relatorio-de-sustentabilidade\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/agenciainfra.com\/blog\/tag\/relatorio-de-sustentabilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/agenciainfra.com\/blog\/"},{"@type":"ListItem","position":2,"name":"relat\u00f3rio de sustentabilidade"}]},{"@type":"WebSite","@id":"https:\/\/agenciainfra.com\/blog\/#website","url":"https:\/\/agenciainfra.com\/blog\/","name":"Ag\u00eancia iNFRA","description":"Multiplataforma de informa\u00e7\u00e3o jornal\u00edstica refer\u00eancia na \u00e1rea de infraestrutura no Brasil!","publisher":{"@id":"https:\/\/agenciainfra.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agenciainfra.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/agenciainfra.com\/blog\/#organization","name":"Ag\u00eancia iNFRA","url":"https:\/\/agenciainfra.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","contentUrl":"https:\/\/agenciainfra.com\/blog\/wp-content\/uploads\/2023\/09\/iNFRA_5-e1761735885940.png","width":1672,"height":454,"caption":"Ag\u00eancia iNFRA"},"image":{"@id":"https:\/\/agenciainfra.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ageninfra","https:\/\/x.com\/agencia_infra","https:\/\/www.linkedin.com\/company\/ag\u00eanciainfra\/","https:\/\/www.instagram.com\/agenciainfra\/"]}]}},"_links":{"self":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/tags\/20049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/agenciainfra.com\/blog\/wp-json\/wp\/v2\/posts?tags=20049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}